{"id":415,"date":"2023-11-28T11:57:04","date_gmt":"2023-11-28T10:57:04","guid":{"rendered":"https:\/\/phalansterre.org\/?p=415"},"modified":"2023-11-28T11:57:04","modified_gmt":"2023-11-28T10:57:04","slug":"marine-is-coming","status":"publish","type":"post","link":"https:\/\/phalansterre.org\/index.php\/2023\/11\/28\/marine-is-coming\/","title":{"rendered":"Marine is coming !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si la \u00ab\u00a0<a href=\"https:\/\/www.seuil.com\/ouvrage\/la-france-d-apres-tableau-politique-jerome-fourquet\/9782021542493\">France d\u2019apr\u00e8s<\/a>\u00a0\u00bb de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/J\u00e9r\u00f4me_Fourquet\">J\u00e9r\u00f4me Fourquet<\/a> ressemble beaucoup \u00e0 la \u00ab\u00a0<a href=\"https:\/\/www.seuil.com\/ouvrage\/la-france-sous-nos-yeux-jerome-fourquet\/9782021481563\">France sous nos yeux<\/a>\u00a0\u00bb et \u00e0 \u00ab\u00a0<a href=\"https:\/\/www.seuil.com\/ouvrage\/l-archipel-francais-jerome-fourquet\/9782021406023\">L\u2019Archipel fran\u00e7ais<\/a>\u00a0\u00bb, ce livre pr\u00e9sente n\u00e9anmoins un triple int\u00e9r\u00eat.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Premi\u00e8rement, il fait vivre les grilles d\u2019analyse d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Emmanuel_Todd\">Emmanuel Todd<\/a> et de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Christophe_Guilluy\">Christophe Guilluy<\/a>. Dans une p\u00e9riode o\u00f9 ils ont \u00e9t\u00e9 largement attaqu\u00e9s et ce, comme si il \u00e9tait malvenu d\u2019enfin prendre en compte la vie, les affects et les comportements politiques des personnes qui peuplent 70% de notre territoire. D\u00e9crire inlassablement les habitants de la France moche, p\u00e9riph\u00e9rique et rurale est une mission en soi tant notre soci\u00e9t\u00e9 est compartiment\u00e9e et tant les gens de pouvoir sont \u00e9loign\u00e9s des ces r\u00e9alit\u00e9s.\u00a0<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a97a12fdb232&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97a12fdbfa7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97a12fdbfa7\" class=\"wp-block-image size-large wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"926\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"417\" src=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7992-926x1024.jpeg\" alt=\"\" class=\"wp-image-417\" srcset=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7992-926x1024.jpeg 926w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7992-271x300.jpeg 271w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7992-768x849.jpeg 768w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7992-1389x1536.jpeg 1389w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7992.jpeg 1746w\" sizes=\"(max-width: 926px) 100vw, 926px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"418\" src=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-1024x1024.jpeg\" alt=\"\" class=\"wp-image-418\" srcset=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-1024x1024.jpeg 1024w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-300x300.jpeg 300w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-150x150.jpeg 150w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-768x768.jpeg 768w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-1536x1536.jpeg 1536w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7390-2048x2048.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"419\" src=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-1024x1024.jpeg\" alt=\"\" class=\"wp-image-419\" srcset=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-1024x1024.jpeg 1024w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-300x300.jpeg 300w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-150x150.jpeg 150w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-768x768.jpeg 768w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-1536x1536.jpeg 1536w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_7198-2048x2048.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"420\" src=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_5662-768x1024.jpeg\" alt=\"\" class=\"wp-image-420\" srcset=\"https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_5662-768x1024.jpeg 768w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_5662-225x300.jpeg 225w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_5662-1152x1536.jpeg 1152w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_5662-1536x2048.jpeg 1536w, https:\/\/phalansterre.org\/wp-content\/uploads\/2023\/11\/IMG_5662-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Deuxi\u00e8mement,\u00a0 ce livre ent\u00e9rine le constat d\u2019un paysage politique tripartite : <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nouvelle_Union_populaire_\u00e9cologique_et_sociale\">NUPES<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Rassemblement_national\">RN<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Renaissance_(parti)\">Renaissance<\/a> et apparent\u00e9s. C\u2019est en effet fondamental pour comprendre que tant que nous verrons la vie politique avec d\u2019anciennes lunettes nous ne serons jamais \u00e0 m\u00eame de prendre les bonnes d\u00e9cisions. Faire comme si les <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Les_R\u00e9publicains\">LR<\/a> et le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Parti_socialiste_(France)\">PS<\/a> existaient encore est une erreur qui nous m\u00e8nera \u00e0 la prise de pouvoir du RN dans notre pays. Verser des larmes de crocodiles \u00e0 ce moment l\u00e0 ne servira plus \u00e0 rien, avoir des remords d\u2019avoir privil\u00e9gi\u00e9 ses int\u00e9r\u00eats politiques au d\u00e9triment de l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral non plus.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Car c\u2019est ce troisi\u00e8me point qui fait une bonne partie de l\u2019int\u00e9r\u00eat du livre. Il nous montre en effet tr\u00e8s pr\u00e9cis\u00e9ment sur les derni\u00e8res 150 pages comment, malgr\u00e9 toutes les vicissitudes de sa vie interne, le RN n\u2019a cess\u00e9 de se renforcer et de gagner du terrain (au sens propre et au sens figur\u00e9) depuis 40 ans. Les jeunes en \u00e2ge de voter qui d\u00e9filaient dans la rue en 2002 (1 300 000 personnes tout de m\u00eame) sont presque la moiti\u00e9 \u00e0 voter RN aujourd\u2019hui. Elle est loin la jeunesse qui emmerdait le Front National !\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors nous pouvons, comme d\u2019habitude, faire semblant de ne pas comprendre ce qui est en train de se passer. Continuer d&#8217;ignorer la dynamique \u00e0 l\u2019oeuvre en Europe et dans le monde. Trouver des milliers d\u2019arguments fallacieux pour surtout \u00e9viter de s\u2019unir et d\u2019\u00e9couter ce que disent nos compatriotes. Pourtant des gens auront pris la peine de tenter de d\u00e9crire ce qui est en train de\u00a0 se passer\u2026 comment expliquerons nous que nous ne les avons pas \u00e9couter ?\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"J\u00e9r\u00f4me Fourquet - La France d&#039;apr\u00e8s - tableau politique\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/OaRo2Dg7_9A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si la \u00ab\u00a0France d\u2019apr\u00e8s\u00a0\u00bb de J\u00e9r\u00f4me Fourquet ressemble beaucoup \u00e0 la \u00ab\u00a0France sous nos yeux\u00a0\u00bb et \u00e0 \u00ab\u00a0L\u2019Archipel fran\u00e7ais\u00a0\u00bb, ce&#8230;<\/p>\n","protected":false},"author":1,"featured_media":421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[9,8],"tags":[],"class_list":["post-415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-politique","category-sociologie-politique"],"_links":{"self":[{"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/posts\/415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/comments?post=415"}],"version-history":[{"count":1,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/posts\/415\/revisions"}],"predecessor-version":[{"id":422,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/posts\/415\/revisions\/422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/media\/421"}],"wp:attachment":[{"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/media?parent=415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/categories?post=415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phalansterre.org\/index.php\/wp-json\/wp\/v2\/tags?post=415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}